{"id":125377,"date":"2017-06-14T17:46:38","date_gmt":"2017-06-14T16:46:38","guid":{"rendered":"https:\/\/joyana.fr\/?p=125377"},"modified":"2017-06-14T17:46:38","modified_gmt":"2017-06-14T16:46:38","slug":"lanieri-vetements-accessoires-made-in-italy","status":"publish","type":"post","link":"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/","title":{"rendered":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy"},"content":{"rendered":"<p>Je vous pr\u00e9sente <a href=\"https:\/\/www.lanieri.com\/\"><strong>Lanieri<\/strong><\/a> \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"125383\" data-permalink=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/lanieri-totallook6_07\/\" data-orig-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?fit=1500%2C1000&amp;ssl=1\" data-orig-size=\"1500,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"LANIERI-TotalLook6_07\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?fit=389%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?fit=1024%2C683&amp;ssl=1\" class=\"alignnone size-full wp-image-125383\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?resize=1500%2C1000&#038;ssl=1\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?w=1500&amp;ssl=1 1500w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook6_07.jpg?resize=600%2C400&amp;ssl=1 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"125378\" data-permalink=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/lanieri-cravatta2_3-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?fit=1500%2C1000&amp;ssl=1\" data-orig-size=\"1500,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"LANIERI-Cravatta2_3-4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?fit=389%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?fit=1024%2C683&amp;ssl=1\" class=\"alignnone size-full wp-image-125378\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?resize=1500%2C1000&#038;ssl=1\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?w=1500&amp;ssl=1 1500w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-Cravatta2_3-4.jpg?resize=600%2C400&amp;ssl=1 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Lanieri.com, la premi\u00e8re boutique e-commerce de v\u00eatements sur-mesure pour Homme Made in Italy, a re\u00e7u le prix du Netcomm ecommerce Award deux ans de suite dans la cat\u00e9gorie \u201cv\u00eatements et accessoires\u201d. Cette ann\u00e9e, Lanieri est l\u2019unique gagnant de sa cat\u00e9gorie, un nouveau but atteint par l&#8217;entreprise de Biella qui a clotur\u00e9 l&#8217;ann\u00e9e 2016 avec une hausse de son chiffre d&#8217;affaire de 200%.<\/p>\n<p>Dans les ann\u00e9es 1990-2000 avoir un costume sur mesure fait en Italie n&#8217;\u00e9tait pas chose facile, aujourd&#8217;hui grace \u00e0 ce genre de service la qualit\u00e9 est \u00e0 port\u00e9e de tous ! Remercions Simone Maggi et Riccardo Schiavotto, co fondateurs de Lanieri.com, le premier e-commerce de costumes sur mesure produits en Italie&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"125380\" data-permalink=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/lanieri-totallook1_03\/\" data-orig-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?fit=900%2C1350&amp;ssl=1\" data-orig-size=\"900,1350\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"LANIERI-TotalLook1_03\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?fit=259%2C389&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?fit=683%2C1024&amp;ssl=1\" class=\"alignnone size-full wp-image-125380\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?resize=900%2C1350&#038;ssl=1\" alt=\"\" width=\"900\" height=\"1350\" srcset=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook1_03.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>En b\u00e9n\u00e9ficiant d&#8217;une technologie et d\u2019une production enti\u00e8rement italiennes, Lanieri utilise uniquement les meilleures laines du march\u00e9 qui sont fournies par des producteurs renomm\u00e9s tels que Reda, Loro Piana, Ermenegildo Zegna, Vitale Barberis Canonico et beaucoup d&#8217;autres. Le concept omnichannel de Lanieri, unique en son genre en Italie, combine la possibilit\u00e9 de r\u00e9aliser sa pi\u00e8ce sur-mesure en ligne sur Lanieri.com mais aussi de b\u00e9n\u00e9ficier d\u2019une exp\u00e9rience dans les Ateliers Lanieri. Aujourd&#8217;hui, Lanieri est pr\u00e9sent \u00e0 Milan, Rome, Turin, Bologne, Biella, Zurich, Bruxelles et Paris.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"125379\" data-permalink=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/lanieri-paris_01\/\" data-orig-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"lanieri-paris_01\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?fit=389%2C292&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?fit=1024%2C768&amp;ssl=1\" class=\"alignnone size-full wp-image-125379\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?resize=1024%2C768&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/lanieri-paris_01.jpg?resize=600%2C450&amp;ssl=1 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Une gamme de prix abordables pour une belle gamme d&#8217;accessoires et v\u00eatements :<br \/>\nCostume : 590\u20ac &#8211; 1040\u20ac, Veste : 440\u20ac &#8211; 740\u20ac, Pantalon : 160\u20ac &#8211; 310\u20ac, Gilet : 170\u20ac &#8211; 340\u20ac, Chemise : 80\u20ac &#8211; 150\u20ac, Blazer : 440\u20ac &#8211; 740\u20ac, Manteau : 690\u20ac &#8211; 1050\u20ac, Tuxedo : 640\u20ac &#8211; 1090\u20ac, Pochette : 25\u20ac &#8211; 39\u20ac, Echarpe : 75\u20ac &#8211; 105\u20ac, Cravate : 55\u20ac &#8211; 105\u20ac, Noeud Papillon : 35\u20ac &#8211; 55\u20ac &#8230;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"125382\" data-permalink=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/lanieri-totallook5_07\/\" data-orig-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&amp;ssl=1\" data-orig-size=\"1700,1133\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"LANIERI-TotalLook5_07\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=389%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1024%2C682&amp;ssl=1\" class=\"alignnone size-full wp-image-125382\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1700%2C1133&#038;ssl=1\" alt=\"\" width=\"1700\" height=\"1133\" srcset=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?w=1700&amp;ssl=1 1700w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=389%2C259&amp;ssl=1 389w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=920%2C613&amp;ssl=1 920w, https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p style=\"text-align: center;\">En savoir + sur <a href=\"https:\/\/www.lanieri.com\/\"><strong>LANIERI<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier&#8230; Lanieri.com, la premi\u00e8re boutique e-commerce de v\u00eatements sur-mesure pour Homme Made in Italy, a re\u00e7u le prix du Netcomm ecommerce Award deux ans de suite dans la cat\u00e9gorie \u201cv\u00eatements [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":125382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,99],"tags":[413,2393,2232,189,429],"class_list":{"0":"post-125377","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mode-homme","8":"category-the-journal","9":"tag-costume","10":"tag-lanieri","11":"tag-mode-homme","12":"tag-sur-mesure","13":"tag-tailoring","14":"entry"},"featured_image_urls":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=389%2C259&ssl=1",389,259,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1700%2C750&ssl=1",1700,750,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C600&ssl=1",600,600,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=920%2C400&ssl=1",920,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=920%2C613&ssl=1",920,613,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable":"<p>Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier&#8230; Lanieri.com, la premi\u00e8re boutique e-commerce de v\u00eatements sur-mesure pour Homme Made in Italy, a re\u00e7u le prix du Netcomm ecommerce Award deux ans de suite dans la cat\u00e9gorie \u201cv\u00eatements et accessoires\u201d. Cette ann\u00e9e, Lanieri est l\u2019unique gagnant de sa cat\u00e9gorie, un nouveau but atteint par l&#8217;entreprise de Biella qui a clotur\u00e9 l&#8217;ann\u00e9e 2016 avec une hausse de son chiffre d&#8217;affaire de 200%. Dans les ann\u00e9es 1990-2000 avoir un costume sur mesure fait en Italie&hellip;<\/p>\n","category_list":"<a href=\"https:\/\/joyana.fr\/en\/category\/blog\/mode-homme\/\" rel=\"category tag\">MODE HOMME<\/a>, <a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" rel=\"category tag\">THE JOURNAL<\/a>","author_info":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/en\/author\/joyana\/"},"comments_num":"3 comments","featured_image_urls_v2":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=389%2C259&ssl=1",389,259,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1700%2C750&ssl=1",1700,750,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C600&ssl=1",600,600,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=920%2C400&ssl=1",920,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=920%2C613&ssl=1",920,613,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable_v2":"<p>Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier&#8230; Lanieri.com, la premi\u00e8re boutique e-commerce de v\u00eatements sur-mesure pour Homme Made in Italy, a re\u00e7u le prix du Netcomm ecommerce Award deux ans de suite dans la cat\u00e9gorie \u201cv\u00eatements et accessoires\u201d. Cette ann\u00e9e, Lanieri est l\u2019unique gagnant de sa cat\u00e9gorie, un nouveau but atteint par l&#8217;entreprise de Biella qui a clotur\u00e9 l&#8217;ann\u00e9e 2016 avec une hausse de son chiffre d&#8217;affaire de 200%. Dans les ann\u00e9es 1990-2000 avoir un costume sur mesure fait en Italie&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/joyana.fr\/en\/category\/blog\/mode-homme\/\" rel=\"category tag\">MODE HOMME<\/a>, <a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" rel=\"category tag\">THE JOURNAL<\/a>","author_info_v2":{"name":"Jo Yana","url":"https:\/\/joyana.fr\/en\/author\/joyana\/"},"comments_num_v2":"3 comments","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy |JO YANA<\/title>\n<meta name=\"description\" content=\"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"ja\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy | JO YANA\" \/>\n<meta property=\"og:description\" content=\"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/\" \/>\n<meta property=\"og:site_name\" content=\"JO YANA\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-14T16:46:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo Yana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:site\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo Yana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\"},\"author\":{\"name\":\"Jo Yana\",\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"headline\":\"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy\",\"datePublished\":\"2017-06-14T16:46:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\"},\"wordCount\":306,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"image\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1\",\"keywords\":[\"Costume\",\"Lanieri\",\"Mode Homme\",\"Sur Mesure\",\"Tailoring\"],\"articleSection\":[\"MODE HOMME\",\"THE JOURNAL\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\",\"url\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\",\"name\":\"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy |JO YANA\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1\",\"datePublished\":\"2017-06-14T16:46:38+00:00\",\"description\":\"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1\",\"width\":1700,\"height\":1133},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.joyana.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joyana.fr\/#website\",\"url\":\"https:\/\/www.joyana.fr\/\",\"name\":\"JO YANA\",\"description\":\"Blog Mode Homme, Lifestyle, D\u00e9co-Design\",\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joyana.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\",\"name\":\"Jo Yana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"width\":343,\"height\":164,\"caption\":\"Jo Yana\"},\"logo\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\"},\"description\":\"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \\\"POUR L'AMOUR DU BEAU\\\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...\",\"sameAs\":[\"https:\/\/joyana.fr\/\"],\"url\":\"https:\/\/joyana.fr\/en\/author\/joyana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy |JO YANA","description":"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/","og_locale":"en_US","og_type":"article","og_title":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy | JO YANA","og_description":"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...","og_url":"https:\/\/joyana.fr\/en\/lanieri-vetements-accessoires-made-in-italy\/125377\/","og_site_name":"JO YANA","article_published_time":"2017-06-14T16:46:38+00:00","og_image":[{"width":1700,"height":1133,"url":"https:\/\/www.joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg","type":"image\/jpeg"}],"author":"Jo Yana","twitter_card":"summary_large_image","twitter_creator":"@Jo_Yana","twitter_site":"@Jo_Yana","twitter_misc":{"Written by":"Jo Yana","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#article","isPartOf":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/"},"author":{"name":"Jo Yana","@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"headline":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy","datePublished":"2017-06-14T16:46:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/"},"wordCount":306,"commentCount":1,"publisher":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"image":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1","keywords":["Costume","Lanieri","Mode Homme","Sur Mesure","Tailoring"],"articleSection":["MODE HOMME","THE JOURNAL"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/","url":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/","name":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy |JO YANA","isPartOf":{"@id":"https:\/\/www.joyana.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage"},"image":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1","datePublished":"2017-06-14T16:46:38+00:00","description":"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier...","breadcrumb":{"@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#primaryimage","url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1","contentUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1","width":1700,"height":1133},{"@type":"BreadcrumbList","@id":"https:\/\/www.joyana.fr\/ja\/lanieri-vetements-accessoires-made-in-italy\/125377\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joyana.fr\/"},{"@type":"ListItem","position":2,"name":"LANIERI \u201cV\u00eatements et Accessoires\u201d Made in Italy"}]},{"@type":"WebSite","@id":"https:\/\/www.joyana.fr\/#website","url":"https:\/\/www.joyana.fr\/","name":"JO YANA","description":"Blog Mode Homme, Lifestyle, D\u00e9co-Design","publisher":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joyana.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c","name":"Jo Yana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/","url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","contentUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","width":343,"height":164,"caption":"Jo Yana"},"logo":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/"},"description":"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \"POUR L'AMOUR DU BEAU\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...","sameAs":["https:\/\/joyana.fr\/"],"url":"https:\/\/joyana.fr\/en\/author\/joyana\/"}]}},"author_meta":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/en\/author\/joyana\/"},"featured_img":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=389%2C259&ssl=1","featured_image_src":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C600&ssl=1","jetpack_featured_media_url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=389%2C259&ssl=1",389,259,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=1700%2C1133&ssl=1",1700,1133,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=1700%2C750&ssl=1",1700,750,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=600%2C600&ssl=1",600,600,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=920%2C400&ssl=1",920,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?fit=920%2C613&ssl=1",920,613,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2017\/06\/LANIERI-TotalLook5_07.jpg?resize=272%2C182&ssl=1",272,182,true]},"uagb_author_info":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/en\/author\/joyana\/"},"uagb_comment_info":14,"uagb_excerpt":"Je vous pr\u00e9sente Lanieri \u201cv\u00eatements et accessoires\u201d Made in Italy, revendus sur un site e-commerce d\u2019\u00e9l\u00e9gance masculine sur-mesure, la qualit\u00e9 tailoring italienne dans le monde entier&#8230; Lanieri.com, la premi\u00e8re boutique e-commerce de v\u00eatements sur-mesure pour Homme Made in Italy, a re\u00e7u le prix du Netcomm ecommerce Award deux ans de suite dans la cat\u00e9gorie \u201cv\u00eatements&hellip;","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/joyana.fr\/en\/category\/blog\/mode-homme\/\" class=\"advgb-post-tax-term\">MODE HOMME<\/a>","<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">THE JOURNAL<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">MODE HOMME<\/span>","<span class=\"advgb-post-tax-term\">THE JOURNAL<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">Costume<\/a>","<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">Lanieri<\/a>","<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">Mode Homme<\/a>","<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">Sur Mesure<\/a>","<a href=\"https:\/\/joyana.fr\/en\/category\/the-journal\/\" class=\"advgb-post-tax-term\">Tailoring<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Costume<\/span>","<span class=\"advgb-post-tax-term\">Lanieri<\/span>","<span class=\"advgb-post-tax-term\">Mode Homme<\/span>","<span class=\"advgb-post-tax-term\">Sur Mesure<\/span>","<span class=\"advgb-post-tax-term\">Tailoring<\/span>"]}},"comment_count":3,"relative_dates":{"created":"Posted 9 years ago","modified":"Updated 9 years ago"},"absolute_dates":{"created":"Posted on 14 June 2017","modified":"Updated on 14 June 2017"},"absolute_dates_time":{"created":"Posted on 14 June 2017 17:46","modified":"Updated on 14 June 2017 17:46"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bteI-wCd","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/posts\/125377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/comments?post=125377"}],"version-history":[{"count":1,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/posts\/125377\/revisions"}],"predecessor-version":[{"id":125384,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/posts\/125377\/revisions\/125384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/media\/125382"}],"wp:attachment":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/media?parent=125377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/categories?post=125377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/tags?post=125377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}