{"id":673,"count":2,"description":"","link":"https:\/\/joyana.fr\/en\/tag\/neoprene\/","name":"N\u00e9opr\u00e8ne","slug":"neoprene","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e9opr\u00e8ne Archives - JO YANA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joyana.fr\/tag\/neoprene\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"ja\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e9opr\u00e8ne Archives - JO YANA\" \/>\n<meta property=\"og:site_name\" content=\"JO YANA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Jo_Yana\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.joyana.fr\/tag\/neoprene\/\",\"url\":\"https:\/\/www.joyana.fr\/tag\/neoprene\/\",\"name\":\"N\u00e9opr\u00e8ne Archives - JO YANA\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.joyana.fr\/tag\/neoprene\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.joyana.fr\/tag\/neoprene\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.joyana.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e9opr\u00e8ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joyana.fr\/#website\",\"url\":\"https:\/\/www.joyana.fr\/\",\"name\":\"JO YANA\",\"description\":\"Blog Mode Homme, Lifestyle, D\u00e9co-Design\",\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joyana.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\",\"name\":\"Jo Yana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"width\":343,\"height\":164,\"caption\":\"Jo Yana\"},\"logo\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\"},\"description\":\"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \\\"POUR L'AMOUR DU BEAU\\\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...\",\"sameAs\":[\"https:\/\/joyana.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e9opr\u00e8ne Archives - JO YANA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joyana.fr\/tag\/neoprene\/","og_locale":"en_US","og_type":"article","og_title":"N\u00e9opr\u00e8ne Archives - JO YANA","og_site_name":"JO YANA","twitter_card":"summary_large_image","twitter_site":"@Jo_Yana","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.joyana.fr\/tag\/neoprene\/","url":"https:\/\/www.joyana.fr\/tag\/neoprene\/","name":"N\u00e9opr\u00e8ne Archives - JO YANA","isPartOf":{"@id":"https:\/\/www.joyana.fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.joyana.fr\/tag\/neoprene\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joyana.fr\/tag\/neoprene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joyana.fr\/"},{"@type":"ListItem","position":2,"name":"N\u00e9opr\u00e8ne"}]},{"@type":"WebSite","@id":"https:\/\/www.joyana.fr\/#website","url":"https:\/\/www.joyana.fr\/","name":"JO YANA","description":"Blog Mode Homme, Lifestyle, D\u00e9co-Design","publisher":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joyana.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c","name":"Jo Yana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/","url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","contentUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","width":343,"height":164,"caption":"Jo Yana"},"logo":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/"},"description":"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \"POUR L'AMOUR DU BEAU\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...","sameAs":["https:\/\/joyana.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/tags\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/joyana.fr\/en\/wp-json\/wp\/v2\/posts?tags=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}