{"id":112949,"date":"2013-04-03T17:41:59","date_gmt":"2013-04-03T16:41:59","guid":{"rendered":"https:\/\/joyana.fr\/?p=12949"},"modified":"2013-04-03T17:41:59","modified_gmt":"2013-04-03T16:41:59","slug":"suspension-design-arianna-par-baldessari-e-baldessari","status":"publish","type":"post","link":"https:\/\/joyana.fr\/ja\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/","title":{"rendered":"Suspension design ARIANNA par BALDESSARI e BALDESSARI"},"content":{"rendered":"<p>L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension <strong>ARIANNA<\/strong> &#8211; sign\u00e9e par <strong>BALDESSARI e BALDESSARI<\/strong> pour <strong>Pallucco<\/strong>&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-12950\" alt=\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lamp-_Baldessari-e-Baldessari_Pallucco-2013-HR.jpg?resize=576%2C864&#038;ssl=1\" width=\"576\" height=\"864\" \/><\/p>\n<p><strong>ARIANNA<\/strong> est un sublime <strong>luminaire<\/strong>, un objet de beaut\u00e9 sophistiqu\u00e9e qui impressionne au premier coup d&#8217;oeil ! Tel un jeu d&#8217;\u00e9clairage innovant cette <strong>suspension<\/strong> arbore une structure architecturale incroyable, renforc\u00e9e par la lumi\u00e8re directe et indirecte, qui se reporte \u00e0 l&#8217;espace environnant gr\u00e2ce aux effets d&#8217;ombre et de lumi\u00e8re&#8230;<\/p>\n<p>Faite en tiges de bois de cerisier t\u00e9lescopiques et d&#8217;une structure centrale chrome nacr\u00e9. Lampe extensible de minimum de 160 mm \u00e0 un maximum de 960 mm !<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-large wp-image-12951\" alt=\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lamp-closed_Baldessari-e-Baldessari_Pallucco-2013_HR.jpg?resize=576%2C864&#038;ssl=1\" width=\"576\" height=\"864\" \/><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-large wp-image-12952\" alt=\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=576%2C412&#038;ssl=1\" width=\"576\" height=\"412\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12953\" alt=\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-e-Baldessari_Pallucco-2013_HR.jpg?resize=576%2C701&#038;ssl=1\" width=\"576\" height=\"701\" \/><\/p>\n<p style=\"text-align: center;\">En savoir + sur <a title=\"PALLUCCO\" href=\"http:\/\/www.pallucco.com\/default.aspx?lng=3&#038;voc=1&#038;cat=1&#038;sel=0\" target=\"_blank\"><strong>PALLUCCO<\/strong><\/a> &#038; <a href=\"http:\/\/www.baldessariebaldessari.it\" target=\"_blank\"><strong>BALDESSARI e BALDESSAR<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension ARIANNA &#8211; sign\u00e9e par  [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":112952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[905,917,1023],"tags":[1316,78,1317,1318],"class_list":{"0":"post-112949","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deco-design","8":"category-luminaire","9":"category-suspension","10":"tag-baldessari-e-baldessari","11":"tag-design","12":"tag-pallucco","13":"tag-suspension-design","14":"entry"},"featured_image_urls":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=389%2C278&ssl=1",389,278,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C465&ssl=1",650,465,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C465&ssl=1",600,465,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=360%2C465&ssl=1",360,465,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C400&ssl=1",650,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable":"<p>L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension ARIANNA &#8211; s&hellip;<\/p>\n","category_list":"<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/\" rel=\"category tag\">DECO-DESIGN<\/a>, <a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/\" rel=\"category tag\">Luminaire<\/a>, <a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" rel=\"category tag\">Suspension<\/a>","author_info":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/ja\/author\/joyana\/"},"comments_num":"3 comments","featured_image_urls_v2":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=389%2C278&ssl=1",389,278,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C465&ssl=1",650,465,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C465&ssl=1",600,465,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=360%2C465&ssl=1",360,465,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C400&ssl=1",650,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable_v2":"<p>L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension ARIANNA &#8211; s&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/\" rel=\"category tag\">DECO-DESIGN<\/a>, <a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/\" rel=\"category tag\">Luminaire<\/a>, <a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" rel=\"category tag\">Suspension<\/a>","author_info_v2":{"name":"Jo Yana","url":"https:\/\/joyana.fr\/ja\/author\/joyana\/"},"comments_num_v2":"3 comments","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA\" \/>\n<meta property=\"og:description\" content=\"L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension ARIANNA &#8211; sign\u00e9e par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joyana.fr\/ja\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\" \/>\n<meta property=\"og:site_name\" content=\"JO YANA\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-03T16:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo Yana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:site\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo Yana\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\"},\"author\":{\"name\":\"Jo Yana\",\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"headline\":\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\",\"datePublished\":\"2013-04-03T16:41:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\"},\"wordCount\":121,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"image\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1\",\"keywords\":[\"BALDESSARI e BALDESSARI\",\"DESIGN\",\"Pallucco\",\"Suspension design\"],\"articleSection\":[\"DECO-DESIGN\",\"Luminaire\",\"Suspension\"],\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\",\"url\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\",\"name\":\"Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1\",\"datePublished\":\"2013-04-03T16:41:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1\",\"width\":650,\"height\":465},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.joyana.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspension design ARIANNA par BALDESSARI e BALDESSARI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joyana.fr\/#website\",\"url\":\"https:\/\/www.joyana.fr\/\",\"name\":\"JO YANA\",\"description\":\"Blog Mode Homme, Lifestyle, D\u00e9co-Design\",\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joyana.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\",\"name\":\"Jo Yana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"width\":343,\"height\":164,\"caption\":\"Jo Yana\"},\"logo\":{\"@id\":\"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/\"},\"description\":\"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \\\"POUR L'AMOUR DU BEAU\\\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...\",\"sameAs\":[\"https:\/\/joyana.fr\/\"],\"url\":\"https:\/\/joyana.fr\/ja\/author\/joyana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/","og_locale":"ja_JP","og_type":"article","og_title":"Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA","og_description":"L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#8217;arachn\u00e9enne suspension ARIANNA &#8211; sign\u00e9e par [&hellip;]","og_url":"https:\/\/joyana.fr\/ja\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/","og_site_name":"JO YANA","article_published_time":"2013-04-03T16:41:59+00:00","og_image":[{"width":650,"height":465,"url":"https:\/\/www.joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg","type":"image\/jpeg"}],"author":"Jo Yana","twitter_card":"summary_large_image","twitter_creator":"@Jo_Yana","twitter_site":"@Jo_Yana","twitter_misc":{"\u57f7\u7b46\u8005":"Jo Yana","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#article","isPartOf":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/"},"author":{"name":"Jo Yana","@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"headline":"Suspension design ARIANNA par BALDESSARI e BALDESSARI","datePublished":"2013-04-03T16:41:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/"},"wordCount":121,"commentCount":1,"publisher":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"image":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1","keywords":["BALDESSARI e BALDESSARI","DESIGN","Pallucco","Suspension design"],"articleSection":["DECO-DESIGN","Luminaire","Suspension"],"inLanguage":"ja","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/","url":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/","name":"Suspension design ARIANNA par BALDESSARI e BALDESSARI - JO YANA","isPartOf":{"@id":"https:\/\/www.joyana.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage"},"image":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1","datePublished":"2013-04-03T16:41:59+00:00","breadcrumb":{"@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#primaryimage","url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1","contentUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1","width":650,"height":465},{"@type":"BreadcrumbList","@id":"https:\/\/www.joyana.fr\/en\/suspension-design-arianna-par-baldessari-e-baldessari\/112949\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joyana.fr\/"},{"@type":"ListItem","position":2,"name":"Suspension design ARIANNA par BALDESSARI e BALDESSARI"}]},{"@type":"WebSite","@id":"https:\/\/www.joyana.fr\/#website","url":"https:\/\/www.joyana.fr\/","name":"JO YANA","description":"Blog Mode Homme, Lifestyle, D\u00e9co-Design","publisher":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joyana.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":["Person","Organization"],"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c","name":"Jo Yana","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/","url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","contentUrl":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","width":343,"height":164,"caption":"Jo Yana"},"logo":{"@id":"https:\/\/www.joyana.fr\/#\/schema\/person\/image\/"},"description":"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \"POUR L'AMOUR DU BEAU\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...","sameAs":["https:\/\/joyana.fr\/"],"url":"https:\/\/joyana.fr\/ja\/author\/joyana\/"}]}},"author_meta":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/ja\/author\/joyana\/"},"featured_img":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=389%2C278&ssl=1","featured_image_src":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C465&ssl=1","jetpack_featured_media_url":"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,false],"thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=389%2C278&ssl=1",389,278,true],"medium_large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"large":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"1536x1536":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"2048x2048":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"featured-thumb":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C465&ssl=1",650,465,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C400&ssl=1",600,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=600%2C465&ssl=1",600,465,true],"author-pro-image":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=360%2C465&ssl=1",360,465,true],"slider":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=650%2C400&ssl=1",650,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?fit=650%2C465&ssl=1",650,465,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/2013\/04\/Arianna-lampopen_Baldessari-Baldessari_Pallucco-2013_HR.jpg?resize=272%2C182&ssl=1",272,182,true]},"uagb_author_info":{"display_name":"Jo Yana","author_link":"https:\/\/joyana.fr\/ja\/author\/joyana\/"},"uagb_comment_info":3,"uagb_excerpt":"L&#8217;\u00e9quipe a eu un v\u00e9ritable coup de coeur pour l&#&hellip;","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/\" class=\"advgb-post-tax-term\">DECO-DESIGN<\/a>","<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/\" class=\"advgb-post-tax-term\">Luminaire<\/a>","<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" class=\"advgb-post-tax-term\">Suspension<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">DECO-DESIGN<\/span>","<span class=\"advgb-post-tax-term\">Luminaire<\/span>","<span class=\"advgb-post-tax-term\">Suspension<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" class=\"advgb-post-tax-term\">BALDESSARI e BALDESSARI<\/a>","<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" class=\"advgb-post-tax-term\">DESIGN<\/a>","<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" class=\"advgb-post-tax-term\">Pallucco<\/a>","<a href=\"https:\/\/joyana.fr\/ja\/category\/deco-design\/luminaire\/suspension\/\" class=\"advgb-post-tax-term\">Suspension design<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">BALDESSARI e BALDESSARI<\/span>","<span class=\"advgb-post-tax-term\">DESIGN<\/span>","<span class=\"advgb-post-tax-term\">Pallucco<\/span>","<span class=\"advgb-post-tax-term\">Suspension design<\/span>"]}},"comment_count":3,"relative_dates":{"created":"Posted 13\u5e74 ago","modified":"Updated 13\u5e74 ago"},"absolute_dates":{"created":"Posted on 3 4\u6708 2013","modified":"Updated on 3 4\u6708 2013"},"absolute_dates_time":{"created":"Posted on 3 4\u6708 2013 17:41","modified":"Updated on 3 4\u6708 2013 17:41"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bteI-tnL","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/posts\/112949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/comments?post=112949"}],"version-history":[{"count":0,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/posts\/112949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/media\/112952"}],"wp:attachment":[{"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/media?parent=112949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/categories?post=112949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joyana.fr\/ja\/wp-json\/wp\/v2\/tags?post=112949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}